{"id":197262,"date":"2023-07-12T14:23:34","date_gmt":"2023-07-12T14:23:34","guid":{"rendered":"https:\/\/www.partypoker.com\/blog?p=197262"},"modified":"2023-07-12T14:23:34","modified_gmt":"2023-07-12T14:23:34","slug":"os-melhores-jogadores-do-omaha-holdem-do-mundo","status":"publish","type":"post","link":"https:\/\/www.partypoker.com\/blog\/pt-br\/os-melhores-jogadores-do-omaha-holdem-do-mundo.html","title":{"rendered":"Os melhores jogadores do Omaha Hold&#8217;em do mundo"},"content":{"rendered":"<p>O <a href=\"https:\/\/www.partypoker.com\/pt-br\/how-to-play\/games\/omaha\/index\">Omaha Hold&#8217;em<\/a> \u00e9 uma variante do poker que tem ganhado cada vez mais popularidade ao redor do mundo. Assim como o Texas Hold&#8217;em, a vers\u00e3o mais conhecida do jogo, \u00e9 jogado com cartas comunit\u00e1rias e tem como objetivo formar a melhor m\u00e3o de cinco cartas poss\u00edvel. No entanto, cada jogador recebe quatro cartas fechadas, o que permite uma gama maior de possibilidades de combina\u00e7\u00f5es.<\/p>\n<p>Dito isso, o Omaha Hold&#8217;em tem seus pr\u00f3prios \u00edcones e lendas, jogadores que se destacaram pela habilidade e t\u00e9cnica, levando o jogo a outro n\u00edvel. A seguir, vamos citar alguns dos melhores jogadores de Omaha Hold&#8217;em de todos os tempos, nomes que certamente s\u00e3o uma inspira\u00e7\u00e3o para aqueles que buscam uma trajet\u00f3ria de sucesso nesta vertente do esporte da mente.<\/p>\n<p><strong>Tommy Le<\/strong><\/p>\n<p>Poucos jogadores s\u00e3o t\u00e3o bem-sucedidos no Omaha quanto o norte americano Tommy Le, ou Tommy Legend, como \u00e9 conhecido. Ele j\u00e1 foi campe\u00e3o de eventos de PLO tanto no World Series of Poker, em duas oportunidades (2017 e 2021), quanto no World Poker Tour, em 2016. Segundo o site The Hendon Mob, Le j\u00e1 faturou mais de US$ 3 milh\u00f5es no Omaha, sendo recordista em todos os tempos.<\/p>\n<p><strong>Phil Galfond\u00a0<\/strong><\/p>\n<p>Considerado um dos jogadores mais t\u00e9cnicos de Omaha Hold&#8217;em, Phil Galfond \u00e9 conhecido por ser um estrategista imbat\u00edvel e um dos mais consistentes jogadores do mundo. Ele \u00e9 dono de tr\u00eas braceletes do WSOP, dois deles no Pot Limit Omaha, em 2008 e 2018, entre muitos outros feitos na modalidade. Al\u00e9m de ser um dos principais nomes do jogo, ele \u00e9 tamb\u00e9m um dos mais respeitados treinadores e mentores do poker atual.<\/p>\n<p><strong>Patrik Antonius\u00a0<\/strong><\/p>\n<p>O finland\u00eas Patrik Antonius \u00e9 um dos jogadores mais experientes e vitoriosos do Omaha Hold&#8217;em, al\u00e9m de ser perito em cash games. Com um curr\u00edculo invej\u00e1vel, ele j\u00e1 conquistou diversos t\u00edtulos em torneios ao redor do mundo, especialmente no PLO. Em 2009, derrotou o sueco Viktor Blom em um dos campeonatos com maior pote acumulado j\u00e1 feito, cerca de US$ 1,35 milh\u00e3o.<\/p>\n<p><strong>Viktor Blom\u00a0<\/strong><\/p>\n<p>Por falar no sueco, Viktor Blom, tamb\u00e9m conhecido como &#8220;Isildur1&#8221;, \u00e9 um jogador que ficou conhecido por sua habilidade e agressividade nas mesas de Omaha Hold&#8217;em \u2013 al\u00e9m de ser um mito do jogo online. Considerado um dos principais nomes da nova gera\u00e7\u00e3o de jogadores, ele se notabilizou por disputar torneios PLO High Roller, conseguindo \u00f3timos resultados no Poker Masters de 2020, por exemplo.<\/p>\n<p><strong>Phil Ivey\u00a0<\/strong><\/p>\n<p>Um dos maiores nomes na hist\u00f3ria do esporte da mente, <a href=\"https:\/\/www.partypoker.com\/blog\/pt-br\/a-trajetoria-de-phil-ivey-no-poker-profissional.html\">Phil Ivey<\/a> tamb\u00e9m \u00e9 um ex\u00edmio jogador de Omaha, embora seja mais conhecido por sua atua\u00e7\u00e3o no Texas Hold&#8217;em. Tr\u00eas de seus dez braceletes conquistados at\u00e9 hoje vieram no Omaha, inclusive o primeiro, vencido em 2000, em Las Vegas. Ele tamb\u00e9m possui um t\u00edtulo no <a href=\"https:\/\/www.partypoker.com\/blog\/pt-br\/conheca-o-poker-horse-cinco-jogos-de-uma-vez.html\">H.O.R.S.E.<\/a>, modalidade mista que envolve, entre outras, o Omaha Hi Lo.<\/p>\n<p><strong>Tom Dwan<\/strong><\/p>\n<p>Tamb\u00e9m conhecido como &#8220;Durrrr&#8221;, o norte-americano Tom Dwan \u00e9 uma lenda viva do poker online e um dos jogadores mais conhecidos, tanto por sua habilidade quanto por seu estilo agressivo de jogo. Em 2022, ele venceu o Triton Omaha, torneio High Roller disputado na Espanha, levando pouco mais de US$ 306 mil pra casa e se consolidando como um dos nomes mais promissores do jogo com quatro cartas.<\/p>\n<p><strong>Ben Lamb<\/strong><\/p>\n<p>O norte-americano Ben Lamb \u00e9 aquilo que se pode chamar de especialista em PLO, sendo o segundo jogador que mais faturou pr\u00eamios na modalidade no WSOP. Por l\u00e1, j\u00e1 disputou diversos torneios de Omaha, tendo conquistado seu primeiro e \u00fanico bracelete nesta vertente em 2011, al\u00e9m de outros ITM.<\/p>\n<p><strong>Jason Mercier<\/strong><\/p>\n<p>Outro especialista em Omaha \u00e9 o norte-americano Jason Mercier, dono de cinco braceletes do WSOP, dois deles do PLO (2009 e 2011) e um no H.O.R.S.E. (2016). Al\u00e9m disso, foi campe\u00e3o do L.A. Poker Classic Omaha em 2009, sendo essa uma de suas primeiras conquistas da carreira profissional.<\/p>\n<p><strong>Loren Klein<\/strong><\/p>\n<p>O veterano Loren Klein fecha a lista como um dos grandes nomes do Omaha na hist\u00f3ria. Cinco das dez maiores conquistas de sua carreira vieram no Omaha, inclusive tr\u00eas braceletes do World Series (um deles em disputa mista) e dois vice-campeonatos, fazendo dele uma das grandes refer\u00eancias em Omaha no mundo do poker.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Omaha Hold&#8217;em \u00e9 uma variante do poker que tem ganhado cada vez mais popularidade ao redor do mundo. Assim como o Texas Hold&#8217;em, a vers\u00e3o mais conhecida do jogo, \u00e9 jogado com cartas comunit\u00e1rias e tem como objetivo formar a melhor m\u00e3o de cinco cartas poss\u00edvel. No entanto, cada jogador recebe quatro cartas fechadas,<\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.partypoker.com\/blog\/pt-br\/os-melhores-jogadores-do-omaha-holdem-do-mundo.html\" title=\"Ler mais\">Ler mais<\/a><\/div>\n","protected":false},"author":262,"featured_media":197267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1491],"tags":[],"yst_prominent_words":[24597,2264,20199,15762,34490,2262,2348],"_links":{"self":[{"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/197262"}],"collection":[{"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/users\/262"}],"replies":[{"embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/comments?post=197262"}],"version-history":[{"count":1,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/197262\/revisions"}],"predecessor-version":[{"id":197296,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/posts\/197262\/revisions\/197296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/media\/197267"}],"wp:attachment":[{"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/media?parent=197262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/categories?post=197262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/tags?post=197262"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.partypoker.com\/blog\/pt-br\/wp-json\/wp\/v2\/yst_prominent_words?post=197262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}